{"id":8,"count":13,"description":"","link":"https:\/\/penguinpetes.com\/wordpress\/category\/biographies\/","name":"Biographies","slug":"biographies","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biographies Archives - Penguin Pete&#039;s Greatest Hits<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/penguinpetes.com\/wordpress\/category\/biographies\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biographies Archives - Penguin Pete&#039;s Greatest Hits\" \/>\n<meta property=\"og:url\" content=\"https:\/\/penguinpetes.com\/wordpress\/category\/biographies\/\" \/>\n<meta property=\"og:site_name\" content=\"Penguin Pete&#039;s Greatest Hits\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Penguin_Pete\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/category\\\/biographies\\\/\",\"url\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/category\\\/biographies\\\/\",\"name\":\"Biographies Archives - Penguin Pete&#039;s Greatest Hits\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/category\\\/biographies\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/category\\\/biographies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biographies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/\",\"name\":\"Penguin Pete&#039;s Greatest Hits\",\"description\":\"Selections from my two decades of freelance writing\",\"publisher\":{\"@id\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/9444fa5a58096bf48bbde50467585e30\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/9444fa5a58096bf48bbde50467585e30\",\"name\":\"Penguin Pete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/PP_avatar-140x140.png\",\"url\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/PP_avatar-140x140.png\",\"contentUrl\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/PP_avatar-140x140.png\",\"width\":140,\"height\":140,\"caption\":\"Penguin Pete\"},\"logo\":{\"@id\":\"https:\\\/\\\/penguinpetes.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/PP_avatar-140x140.png\"},\"description\":\"Take good care of my memes; I've raised them since they were daydreams!\",\"sameAs\":[\"https:\\\/\\\/penguinpetes.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biographies Archives - Penguin Pete&#039;s Greatest Hits","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/penguinpetes.com\/wordpress\/category\/biographies\/","og_locale":"en_US","og_type":"article","og_title":"Biographies Archives - Penguin Pete&#039;s Greatest Hits","og_url":"https:\/\/penguinpetes.com\/wordpress\/category\/biographies\/","og_site_name":"Penguin Pete&#039;s Greatest Hits","twitter_card":"summary_large_image","twitter_site":"@Penguin_Pete","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/penguinpetes.com\/wordpress\/category\/biographies\/","url":"https:\/\/penguinpetes.com\/wordpress\/category\/biographies\/","name":"Biographies Archives - Penguin Pete&#039;s Greatest Hits","isPartOf":{"@id":"https:\/\/penguinpetes.com\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/penguinpetes.com\/wordpress\/category\/biographies\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/penguinpetes.com\/wordpress\/category\/biographies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/penguinpetes.com\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Biographies"}]},{"@type":"WebSite","@id":"https:\/\/penguinpetes.com\/wordpress\/#website","url":"https:\/\/penguinpetes.com\/wordpress\/","name":"Penguin Pete&#039;s Greatest Hits","description":"Selections from my two decades of freelance writing","publisher":{"@id":"https:\/\/penguinpetes.com\/wordpress\/#\/schema\/person\/9444fa5a58096bf48bbde50467585e30"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/penguinpetes.com\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/penguinpetes.com\/wordpress\/#\/schema\/person\/9444fa5a58096bf48bbde50467585e30","name":"Penguin Pete","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/penguinpetes.com\/wordpress\/wp-content\/uploads\/2018\/12\/PP_avatar-140x140.png","url":"https:\/\/penguinpetes.com\/wordpress\/wp-content\/uploads\/2018\/12\/PP_avatar-140x140.png","contentUrl":"https:\/\/penguinpetes.com\/wordpress\/wp-content\/uploads\/2018\/12\/PP_avatar-140x140.png","width":140,"height":140,"caption":"Penguin Pete"},"logo":{"@id":"https:\/\/penguinpetes.com\/wordpress\/wp-content\/uploads\/2018\/12\/PP_avatar-140x140.png"},"description":"Take good care of my memes; I've raised them since they were daydreams!","sameAs":["https:\/\/penguinpetes.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/penguinpetes.com\/wordpress\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/penguinpetes.com\/wordpress\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/penguinpetes.com\/wordpress\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/penguinpetes.com\/wordpress\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}